{"id":45,"date":"2011-01-16T01:06:46","date_gmt":"2011-01-16T01:06:46","guid":{"rendered":"http:\/\/www.kriesi.at\/themes\/propulsion\/?post_type=portfolio&amp;p=45"},"modified":"2011-01-16T01:06:46","modified_gmt":"2011-01-16T01:06:46","slug":"vimeo-video","status":"publish","type":"portfolio","link":"https:\/\/aglow.cz\/index.php\/portfolio-item\/vimeo-video\/","title":{"rendered":"Single Portfolio: Fullscreen Slider"},"content":{"rendered":"<div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-0  el_before_av_textblock  avia-builder-el-first   container_wrap sidebar_right'  ><div  class='avia-slideshow av-av_slideshow_full-c5e5a9e40a887f33cd7493656cb010ae avia-slideshow-no scaling av_slideshow_full avia-slide-slider av-slideshow-ui av-control-default av-slideshow-autoplay av-loop-endless av-loop-manual-endless av-default-height-applied  image_no_stretch avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:true,&quot;loop_autoplay&quot;:&quot;endless&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 60%;'><li  class='avia-slideshow-slide av-av_slideshow_full-c5e5a9e40a887f33cd7493656cb010ae__0  slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img fetchpriority=\"high\" class=\"wp-image-745 avia-img-lazy-loading-not-745\"  src='https:\/\/aglow.cz\/wp-content\/uploads\/2011\/12\/imac_big_demo.png' width='1000' height='600' title='imac_big_demo' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><li  class='avia-slideshow-slide av-av_slideshow_full-c5e5a9e40a887f33cd7493656cb010ae__1  slide-2 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img fetchpriority=\"high\" class=\"wp-image-745 avia-img-lazy-loading-not-745\"  src='https:\/\/aglow.cz\/wp-content\/uploads\/2011\/12\/imac_big_demo.png' width='1000' height='600' title='imac_big_demo' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><\/ul><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='left-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Previous\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-1'>Previous<\/title>\n<desc id='av-svg-desc-1'>Previous<\/desc>\n<path d=\"M14.464 27.84q0.832 0.832 0 1.536-0.832 0.832-1.536 0l-12.544-12.608q-0.768-0.768 0-1.6l12.544-12.608q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-11.456 11.904z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Previous<\/span><\/a><a href='#next' class='next-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='right-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Next\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-2' aria-describedby='av-svg-desc-2' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-2'>Next<\/title>\n<desc id='av-svg-desc-2'>Next<\/desc>\n<path d=\"M0.416 27.84l11.456-11.84-11.456-11.904q-0.832-0.832 0-1.536 0.832-0.832 1.536 0l12.544 12.608q0.768 0.832 0 1.6l-12.544 12.608q-0.704 0.832-1.536 0-0.832-0.704 0-1.536z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Next<\/span><\/a><\/div><div class='avia-slideshow-dots avia-slideshow-controls'><a href='#1' class='goto-slide active' >1<\/a><a href='#2' class='goto-slide ' >2<\/a><\/div><\/div><\/div><div id='after_full_slider_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-45'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-av_textblock-2a2a45fada6eccdf2adfe3591ef7663a '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3 style=\"text-align: center;\">Super nice Lorem Ipsum<\/h3>\n<\/div><\/section>\n<div  class='flex_column av-av_one_half-2a9015ff38129c418a3f2eafba3e9512 av_one_half  avia-builder-el-2  el_after_av_textblock  el_before_av_one_half  first flex_column_div  column-top-margin'     ><section  class='av_textblock_section av-av_textblock-2a2a45fada6eccdf2adfe3591ef7663a '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Lorem ipsum dolor sit amet, consectetuer adipiscing elit. Aenean <a href=\"#\">commodo ligula eget dolor<\/a>. Aenean massa. Cum sociis natoque penatibus et magnis dis parturient montes, nascetur <strong>ridiculus<\/strong> mus. Donec quam felis, ultricies nec, pellentesque eu, pretium quis, sem.<\/p>\n<\/div><\/section><\/div>\n<div  class='flex_column av-av_one_half-7b3f4ae2cd57e40092b7fdeea59115af av_one_half  avia-builder-el-4  el_after_av_one_half  el_before_av_slideshow_full  avia-builder-el-last  flex_column_div  column-top-margin'     ><section  class='av_textblock_section av-av_textblock-2a2a45fada6eccdf2adfe3591ef7663a '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Nulla consequat <strong>massa<\/strong> quis enim. Donec pede justo, fringilla vel, aliquet nec, vulputate eget, arcu. In enim justo, rhoncus ut, imperdiet a, venenatis vitae, justo. Nullam dictum felis eu pede mollis pretium. Integer tincidunt. Cras dapibus. Vivamus elementum semper nisi.<\/p>\n<\/div><\/section><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='full_slider_2'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-6  el_after_av_one_half  el_before_av_textblock   slider-not-first container_wrap sidebar_right'  ><div  class='avia-slideshow av-av_slideshow_full-5fa470cf77e8c99d1c143a257a90ff63 avia-slideshow-no scaling av_slideshow_full avia-slide-slider av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied  image_no_stretch avia-slideshow-2' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 60%;'><li  class='avia-slideshow-slide av-av_slideshow_full-5fa470cf77e8c99d1c143a257a90ff63__0  slide-1 slide-odd'><div data-rel='slideshow-2' class='avia-slide-wrap '   ><img fetchpriority=\"high\" class=\"wp-image-745 avia-img-lazy-loading-not-745\"  src='https:\/\/aglow.cz\/wp-content\/uploads\/2011\/12\/imac_big_demo.png' width='1000' height='600' title='imac_big_demo' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><li  class='avia-slideshow-slide av-av_slideshow_full-5fa470cf77e8c99d1c143a257a90ff63__1  slide-2 slide-even'><div data-rel='slideshow-2' class='avia-slide-wrap '   ><img fetchpriority=\"high\" class=\"wp-image-745 avia-img-lazy-loading-not-745\"  src='https:\/\/aglow.cz\/wp-content\/uploads\/2011\/12\/imac_big_demo.png' width='1000' height='600' title='imac_big_demo' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><\/ul><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='left-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Previous\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-3' aria-describedby='av-svg-desc-3' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-3'>Previous<\/title>\n<desc id='av-svg-desc-3'>Previous<\/desc>\n<path d=\"M14.464 27.84q0.832 0.832 0 1.536-0.832 0.832-1.536 0l-12.544-12.608q-0.768-0.768 0-1.6l12.544-12.608q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-11.456 11.904z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Previous<\/span><\/a><a href='#next' class='next-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='right-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Next\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-4' aria-describedby='av-svg-desc-4' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-4'>Next<\/title>\n<desc id='av-svg-desc-4'>Next<\/desc>\n<path d=\"M0.416 27.84l11.456-11.84-11.456-11.904q-0.832-0.832 0-1.536 0.832-0.832 1.536 0l12.544 12.608q0.768 0.832 0 1.6l-12.544 12.608q-0.704 0.832-1.536 0-0.832-0.704 0-1.536z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Next<\/span><\/a><\/div><div class='avia-slideshow-dots avia-slideshow-controls'><a href='#1' class='goto-slide active' >1<\/a><a href='#2' class='goto-slide ' >2<\/a><\/div><\/div><\/div><div id='after_full_slider_2'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-45'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-av_textblock-2a2a45fada6eccdf2adfe3591ef7663a '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3 style=\"text-align: center;\">Another Slideshow<\/h3>\n<\/div><\/section>\n<div  class='flex_column av-av_one_half-2a9015ff38129c418a3f2eafba3e9512 av_one_half  avia-builder-el-8  el_after_av_textblock  el_before_av_one_half  first flex_column_div  column-top-margin'     ><section  class='av_textblock_section av-av_textblock-2a2a45fada6eccdf2adfe3591ef7663a '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Nulla consequat <strong>massa<\/strong> quis enim. Donec pede justo, fringilla vel, aliquet nec, vulputate eget, arcu. In enim justo, rhoncus ut, imperdiet a, venenatis vitae, justo. Nullam dictum felis eu pede mollis pretium. Integer tincidunt. Cras dapibus. Vivamus elementum semper nisi.<\/p>\n<\/div><\/section><\/div>\n<div  class='flex_column av-av_one_half-7b3f4ae2cd57e40092b7fdeea59115af av_one_half  avia-builder-el-10  el_after_av_one_half  el_before_av_section  avia-builder-el-last  flex_column_div  column-top-margin'     ><section  class='av_textblock_section av-av_textblock-2a2a45fada6eccdf2adfe3591ef7663a '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Lorem ipsum dolor sit amet, consectetuer adipiscing elit. Aenean <a href=\"#\">commodo ligula eget dolor<\/a>. Aenean massa. Cum sociis natoque penatibus et magnis dis parturient montes, nascetur <strong>ridiculus<\/strong> mus. Donec quam felis, ultricies nec, pellentesque eu, pretium quis, sem.<\/p>\n<\/div><\/section><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_1'  class='avia-section av-av_section-860e02eef87feb9b2e0751f470f2bac1 alternate_color avia-section-default avia-shadow  avia-builder-el-12  el_after_av_one_half  avia-builder-el-last  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-45'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-av_textblock-2a2a45fada6eccdf2adfe3591ef7663a '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h4 style=\"text-align: center;\">Most Recent Entries<\/h4>\n<\/div><\/section>\n<div  class='hr av-av_hr-4a566f4a73ae78223e1997276585dc3a hr-short  avia-builder-el-14  el_after_av_textblock  el_before_av_portfolio  avia-builder-el-last  hr-center'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div  id=\"av-sc-portfolio-1\"  class=' grid-sort-container isotope   no_margin-container with-excerpt-container grid-total-even grid-col-4 grid-links-' data-portfolio-id='1'><div data-ajax-id='3806' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-3806 grid-entry-overview grid-loop-1 grid-parity-odd  mesta_sort  av_one_fourth first default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/aglow.cz\/index.php\/portfolio-item\/celakovice\/\" title='\u010cel\u00e1kovice'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/aglow.cz\/wp-content\/uploads\/2019\/09\/\u010cel\u00e1kovice_C\u00edsa\u0159sk\u00e1_Kuchyn\u011b_new_housing-260x185.jpg\" class=\"wp-image-3808 avia-img-lazy-loading-not-3808 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: \u010cel\u00e1kovice\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/aglow.cz\/index.php\/portfolio-item\/celakovice\/' title='\u010cel\u00e1kovice'>\u010cel\u00e1kovice<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='3684' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-3684 grid-entry-overview grid-loop-2 grid-parity-even  mesta_sort  av_one_fourth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/aglow.cz\/index.php\/portfolio-item\/3684\/\" title='?'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/aglow.cz\/wp-content\/uploads\/2019\/04\/P1240261-260x185.jpg\" class=\"wp-image-3718 avia-img-lazy-loading-not-3718 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: ?\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/aglow.cz\/index.php\/portfolio-item\/3684\/' title='?'>?<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='3681' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-3681 grid-entry-overview grid-loop-3 grid-parity-odd  mesta_sort  av_one_fourth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/aglow.cz\/index.php\/portfolio-item\/vysoke-myto\/\" title='Vysok\u00e9 M\u00fdto'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/aglow.cz\/wp-content\/uploads\/2019\/04\/N\u00e1m\u011bst\u00ed_ve_Vysok\u00e9m_M\u00fdt\u011b-260x185.jpg\" class=\"wp-image-3682 avia-img-lazy-loading-not-3682 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Vysok\u00e9 M\u00fdto\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/aglow.cz\/index.php\/portfolio-item\/vysoke-myto\/' title='Vysok\u00e9 M\u00fdto'>Vysok\u00e9 M\u00fdto<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='3675' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-3675 grid-entry-overview grid-loop-4 grid-parity-even  post-entry-last  mesta_sort  av_one_fourth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/aglow.cz\/index.php\/portfolio-item\/pardubice\/\" title='Pardubice'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/aglow.cz\/wp-content\/uploads\/2019\/04\/PardubicePer\u0161t\u00fdnsk\u00e9_n\u00e1m\u011bst\u00ed-260x185.jpg\" class=\"wp-image-3676 avia-img-lazy-loading-not-3676 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Pardubice\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/aglow.cz\/index.php\/portfolio-item\/pardubice\/' title='Pardubice'>Pardubice<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-45'><div class='entry-content-wrapper clearfix'>\n","protected":false},"excerpt":{"rendered":"<p>Add what you want!<\/p>\n","protected":false},"author":2,"featured_media":316,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[24,25,27],"class_list":["post-45","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-html","portfolio_entries-photography","portfolio_entries-video"],"_links":{"self":[{"href":"https:\/\/aglow.cz\/index.php\/wp-json\/wp\/v2\/portfolio\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aglow.cz\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/aglow.cz\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/aglow.cz\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aglow.cz\/index.php\/wp-json\/wp\/v2\/comments?post=45"}],"version-history":[{"count":0,"href":"https:\/\/aglow.cz\/index.php\/wp-json\/wp\/v2\/portfolio\/45\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aglow.cz\/index.php\/wp-json\/wp\/v2\/media\/316"}],"wp:attachment":[{"href":"https:\/\/aglow.cz\/index.php\/wp-json\/wp\/v2\/media?parent=45"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aglow.cz\/index.php\/wp-json\/wp\/v2\/tags?post=45"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/aglow.cz\/index.php\/wp-json\/wp\/v2\/portfolio_entries?post=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}